{"id":1963,"date":"2018-06-18T08:17:23","date_gmt":"2018-06-18T08:17:23","guid":{"rendered":"https:\/\/fincalosaljibes.com\/vinedo\/"},"modified":"2018-09-06T08:19:00","modified_gmt":"2018-09-06T08:19:00","slug":"vinedo","status":"publish","type":"page","link":"https:\/\/fincalosaljibes.com\/en\/vinedo\/","title":{"rendered":"Winery"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;24&#8243; padding_bottom=&#8221;0&#8243; z_index=&#8221;&#8221;][vc_column][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; css=&#8221;.vc_custom_1533713649931{margin-right: 20px !important;margin-left: 10px !important;border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 24px !important;padding-right: 16% !important;padding-bottom: 24px !important;padding-left: 16% !important;background-color: #ffffff !important;border-left-color: #e6e6e6 !important;border-left-style: solid !important;border-right-color: #e6e6e6 !important;border-right-style: solid !important;border-top-color: #e6e6e6 !important;border-top-style: solid !important;border-bottom-color: #e6e6e6 !important;border-bottom-style: solid !important;}&#8221;][vc_column_inner][vc_column_text]<\/p>\n<p style=\"text-align: center;\">The soil of the estate is limy and sandy with little organic material and depth. The climate is arid continental. These extreme conditions, along with the cited high altitude, favour a low production and a lengthy maturation of the grape varieties that grow in the area, bringing roundness and quality to our wines.<\/p>\n<p style=\"text-align: center;\">Although the viticulture in our vineyards has preserved traditional methods, it has also introduced modern techniques and organic farming in order to guarantee a high quality grape production and a sustainable balance between the estate and the winery. In addition, the effort and enthusiasm of our team assure wines of great personality and excellent quality.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">[addtoany]<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;yes&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;24&#8243; z_index=&#8221;&#8221;][vc_column css=&#8221;.vc_custom_1533712979854{padding-left: 24px !important;}&#8221;][vc_column_text]<\/p>\n<style type=\"text\/css\">\n#foogallery-gallery-1567.fg-masonry { --fg-gutter: 10px; }<\/style>\n\t\t\t<style type=\"text\/css\">\n#foogallery-gallery-1567_1.fg-masonry { --fg-gutter: 10px; }<\/style>\n\t\t\t<div class=\"foogallery foogallery-container foogallery-masonry foogallery-lightbox-foobox fg-center fg-masonry fg-ready fg-light fg-loading-default fg-loaded-fade-in fg-hover-fade fg-hover-external fg-col3\" id=\"foogallery-gallery-1567_1\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:true,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true}\" style=\"--fg-title-line-clamp: 0; --fg-description-line-clamp: 0;\" >\n\t\t<div class=\"fg-column-width\"><\/div>\n\t<div class=\"fg-gutter-width\"><\/div>\n\t\t<div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/3vinedo.jpg\" data-attachment-id=\"1568\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"551\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/3vinedo.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221200%22%20height%3D%22551%22%20viewBox%3D%220%200%201200%20551%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/DSCF6038.jpg\" data-attachment-id=\"1571\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"1920\" height=\"1280\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/DSCF6038.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221920%22%20height%3D%221280%22%20viewBox%3D%220%200%201920%201280%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Bodega.jpg\" data-caption-title=\"shooting 09-2007\" data-attachment-id=\"1572\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"shooting 09-2007\" width=\"625\" height=\"417\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Bodega.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22625%22%20height%3D%22417%22%20viewBox%3D%220%200%20625%20417%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">shooting 09-2007<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/BodegaCocheCaballos.jpg\" data-attachment-id=\"1573\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"624\" height=\"416\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/BodegaCocheCaballos.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22624%22%20height%3D%22416%22%20viewBox%3D%220%200%20624%20416%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/1bkg_vinedos.jpg\" data-attachment-id=\"1570\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"1200\" height=\"551\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/1bkg_vinedos.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221200%22%20height%3D%22551%22%20viewBox%3D%220%200%201200%20551%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/3vinedo-copy.jpg\" data-attachment-id=\"1575\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"1200\" height=\"551\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/3vinedo-copy.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221200%22%20height%3D%22551%22%20viewBox%3D%220%200%201200%20551%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_00054.jpg\" data-attachment-id=\"1576\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"1024\" height=\"683\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_00054.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221024%22%20height%3D%22683%22%20viewBox%3D%220%200%201024%20683%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_00570.jpg\" data-attachment-id=\"1577\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"1024\" height=\"683\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_00570.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221024%22%20height%3D%22683%22%20viewBox%3D%220%200%201024%20683%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_03238.jpg\" data-attachment-id=\"1578\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"1024\" height=\"683\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_03238.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221024%22%20height%3D%22683%22%20viewBox%3D%220%200%201024%20683%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/2vinedo.jpg\" data-attachment-id=\"1569\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"1200\" height=\"551\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/2vinedo.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%221200%22%20height%3D%22551%22%20viewBox%3D%220%200%201200%20551%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; row_negative_margin=&#8221;disable_negative_margin&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; z_index=&#8221;&#8221; css=&#8221;.vc_custom_1533713190189{padding-top: 24px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1528195482584{padding-right: 0px !important;padding-left: 0px !important;}&#8221;]<div class=\"qode-banner qode-banner-va-center\"><a class=\"qode-banner-link\" href=\"https:\/\/fincalosaljibes.com\/en\/nuestra-bodega\/\" target=\"_self\"><\/a><div class=\"qode-banner-image\"><img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/bodega.jpg\" alt=\"\" \/><\/div><div class=\"qode-banner-content\"><div class=\"qode-banner-content-inner\"><div class=\"qode-banner-text-holder\">\n<p style=\"text-align: center;\">OUR WINERY<\/p>\n<\/div><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1528195487788{padding-right: 0px !important;padding-left: 0px !important;}&#8221;]<div class=\"qode-banner qode-banner-va-center\"><a class=\"qode-banner-link\" href=\"https:\/\/fincalosaljibes.com\/en\/variedades\/\" target=\"_self\"><\/a><div class=\"qode-banner-image\"><img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/variedades.jpg\" alt=\"\" \/><\/div><div class=\"qode-banner-content\"><div class=\"qode-banner-content-inner\"><div class=\"qode-banner-text-holder\">\n<p style=\"text-align: center;\">VARIETIES<\/p>\n<\/div><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1528195492854{padding-right: 0px !important;padding-left: 0px !important;}&#8221;]<div class=\"qode-banner qode-banner-va-center\"><a class=\"qode-banner-link\" href=\"https:\/\/fincalosaljibes.com\/en\/elaboracion\/\" target=\"_self\"><\/a><div class=\"qode-banner-image\"><img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/elaboracion.jpg\" alt=\"\" \/><\/div><div class=\"qode-banner-content\"><div class=\"qode-banner-content-inner\"><div class=\"qode-banner-text-holder\">\n<p style=\"text-align: center;\">ELABORATION<\/p>\n<\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;24&#8243; padding_bottom=&#8221;24&#8243; z_index=&#8221;&#8221;][vc_column]<div class=\"call_to_action simple\" style=\"background-color: #181818;padding-top: 36px;padding-bottom: 36px;\"><div class=\"container_inner\"><div class=\"text_wrapper column1\"><div class=\"call_to_action_text  font_size_inherit font_weight_inherit\" style=\"font-size:24px;font-weight: 500;\">We invite you to <strong>La Bodega Los Aljibes<\/strong><\/div><a itemprop=\"url\" href=\"\/contacto\/\" class=\"qbutton white medium\" target=\"\" style=\"\" data-hover-background-color=#ffffff data-hover-color=#181818>YES, I WANT<\/a><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;24&#8243; padding_bottom=&#8221;0&#8243; z_index=&#8221;&#8221;][vc_column][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; css=&#8221;.vc_custom_1533713649931{margin-right: 20px !important;margin-left: 10px !important;border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 24px !important;padding-right: 16% !important;padding-bottom: 24px !important;padding-left: 16% !important;background-color: #ffffff !important;border-left-color: #e6e6e6 !important;border-left-style: solid !important;border-right-color: #e6e6e6 !important;border-right-style: solid&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-1963","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Winery | Finca Los Aljibes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fincalosaljibes.com\/en\/vinedo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Winery | Finca Los Aljibes\" \/>\n<meta property=\"og:description\" content=\"[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;24&#8243; padding_bottom=&#8221;0&#8243; z_index=&#8221;&#8221;][vc_column][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; css=&#8221;.vc_custom_1533713649931{margin-right: 20px !important;margin-left: 10px !important;border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 24px !important;padding-right: 16% !important;padding-bottom: 24px !important;padding-left: 16% !important;background-color: #ffffff !important;border-left-color: #e6e6e6 !important;border-left-style: solid !important;border-right-color: #e6e6e6 !important;border-right-style: solid...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fincalosaljibes.com\/en\/vinedo\/\" \/>\n<meta property=\"og:site_name\" content=\"Finca Los Aljibes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bodegalosaljibes\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-06T08:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_02770.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/vinedo\\\/\",\"url\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/vinedo\\\/\",\"name\":\"Winery | Finca Los Aljibes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/#website\"},\"datePublished\":\"2018-06-18T08:17:23+00:00\",\"dateModified\":\"2018-09-06T08:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/vinedo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/vinedo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/vinedo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/\",\"name\":\"Finca Los Aljibes\",\"description\":\"Bodega de vinos, enoturismo, visitas a la bodega y finca para celebrar bodas y eventos\",\"publisher\":{\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/#organization\"},\"alternateName\":\"Bodega Los Aljibes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/#organization\",\"name\":\"Bodega Finca Los Aljibes\",\"alternateName\":\"Bodega Los Aljibes\",\"url\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fincalosaljibes.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/LOGO-FINCA-LOS-ALJIBES.png\",\"contentUrl\":\"https:\\\/\\\/fincalosaljibes.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/LOGO-FINCA-LOS-ALJIBES.png\",\"width\":1207,\"height\":894,\"caption\":\"Bodega Finca Los Aljibes\"},\"image\":{\"@id\":\"https:\\\/\\\/fincalosaljibes.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bodegalosaljibes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/losaljibes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/los-aljibes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqYK8s9Xmfj2C1k6xCGODOw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Winery | Finca Los Aljibes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fincalosaljibes.com\/en\/vinedo\/","og_locale":"en_US","og_type":"article","og_title":"Winery | Finca Los Aljibes","og_description":"[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;24&#8243; padding_bottom=&#8221;0&#8243; z_index=&#8221;&#8221;][vc_column][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; css=&#8221;.vc_custom_1533713649931{margin-right: 20px !important;margin-left: 10px !important;border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 24px !important;padding-right: 16% !important;padding-bottom: 24px !important;padding-left: 16% !important;background-color: #ffffff !important;border-left-color: #e6e6e6 !important;border-left-style: solid !important;border-right-color: #e6e6e6 !important;border-right-style: solid...","og_url":"https:\/\/fincalosaljibes.com\/en\/vinedo\/","og_site_name":"Finca Los Aljibes","article_publisher":"https:\/\/www.facebook.com\/bodegalosaljibes\/","article_modified_time":"2018-09-06T08:19:00+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2018\/08\/Finca_Los_Aljibes_SSC_02770.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fincalosaljibes.com\/en\/vinedo\/","url":"https:\/\/fincalosaljibes.com\/en\/vinedo\/","name":"Winery | Finca Los Aljibes","isPartOf":{"@id":"https:\/\/fincalosaljibes.com\/en\/#website"},"datePublished":"2018-06-18T08:17:23+00:00","dateModified":"2018-09-06T08:19:00+00:00","breadcrumb":{"@id":"https:\/\/fincalosaljibes.com\/en\/vinedo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fincalosaljibes.com\/en\/vinedo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fincalosaljibes.com\/en\/vinedo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fincalosaljibes.com\/en\/"},{"@type":"ListItem","position":2,"name":"Winery"}]},{"@type":"WebSite","@id":"https:\/\/fincalosaljibes.com\/en\/#website","url":"https:\/\/fincalosaljibes.com\/en\/","name":"Finca Los Aljibes","description":"Bodega de vinos, enoturismo, visitas a la bodega y finca para celebrar bodas y eventos","publisher":{"@id":"https:\/\/fincalosaljibes.com\/en\/#organization"},"alternateName":"Bodega Los Aljibes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fincalosaljibes.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fincalosaljibes.com\/en\/#organization","name":"Bodega Finca Los Aljibes","alternateName":"Bodega Los Aljibes","url":"https:\/\/fincalosaljibes.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fincalosaljibes.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2025\/06\/LOGO-FINCA-LOS-ALJIBES.png","contentUrl":"https:\/\/fincalosaljibes.com\/wp-content\/uploads\/2025\/06\/LOGO-FINCA-LOS-ALJIBES.png","width":1207,"height":894,"caption":"Bodega Finca Los Aljibes"},"image":{"@id":"https:\/\/fincalosaljibes.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bodegalosaljibes\/","https:\/\/www.instagram.com\/losaljibes\/","https:\/\/www.linkedin.com\/company\/los-aljibes\/","https:\/\/www.youtube.com\/channel\/UCqYK8s9Xmfj2C1k6xCGODOw"]}]}},"_links":{"self":[{"href":"https:\/\/fincalosaljibes.com\/en\/wp-json\/wp\/v2\/pages\/1963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fincalosaljibes.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fincalosaljibes.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fincalosaljibes.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fincalosaljibes.com\/en\/wp-json\/wp\/v2\/comments?post=1963"}],"version-history":[{"count":0,"href":"https:\/\/fincalosaljibes.com\/en\/wp-json\/wp\/v2\/pages\/1963\/revisions"}],"wp:attachment":[{"href":"https:\/\/fincalosaljibes.com\/en\/wp-json\/wp\/v2\/media?parent=1963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}